{"id":3,"date":"2022-01-21T11:55:58","date_gmt":"2022-01-21T11:55:58","guid":{"rendered":"https:\/\/sb4.brandstory.pt\/wordpress\/?page_id=3"},"modified":"2022-03-09T16:10:26","modified_gmt":"2022-03-09T16:10:26","slug":"politica-de-privacidade-e-cookies","status":"publish","type":"page","link":"https:\/\/ericeiramarket.pt\/en\/politica-de-privacidade-e-cookies\/","title":{"rendered":"Privacy Policy and Cookies"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1855d7c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default row-top\" data-id=\"1855d7c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a593b44 column-style-top\" data-id=\"2a593b44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-924ab19 elementor-widget elementor-widget-heading\" data-id=\"924ab19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">O A RJRI \u2013 A CASA DAS COMUNICA\u00c7\u00d5ES, LDA. (doravante, \u201cRespons\u00e1vel pelo Tratamento\u201d), com sede na Rua Dr. Eduardo Burnay, 71, 2655-368 Ericeira, e NIPC 515734403  \u00e9 propriet\u00e1rio do dom\u00ednio ericeiramarket.pt onde se encontra alojado o seu WEBSITE.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2abd55a2 elementor-widget elementor-widget-text-editor\" data-id=\"2abd55a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O RESPONS\u00c1VEL PELO TRATAMENTO EST\u00c1 EMPENHADO EM PROTEGER A PRIVACIDADE E OS DADOS PESSOAIS DOS SEUS CLIENTES E UTILIZADORES DO WEBSITE, PELO QUE, ELABOROU E ADOTOU A PRESENTE POL\u00cdTICA E AS PR\u00c1TICAS AQUI DESCRITAS. ESTA POL\u00cdTICA DE PRIVACIDADE EXPLICA COMO S\u00c3O RECOLHIDOS E TRATADOS OS SEUS DADOS PESSOAIS, PELO QUE, ACONSELHAMOS A SUA LEITURA PARA CONHECER AS CONDI\u00c7\u00d5ES EM QUE OS SEUS DADOS PESSOAIS S\u00c3O RECOLHIDOS E UTILIZADOS.<\/p>\n<h3><strong>Formul\u00e1rio de pedido de contactos<\/strong><\/h3>\n<ol>\n<li>A RJRI &#8211; A CASA DAS COMUNICA\u00c7\u00d5ES, LDA., com NIPC\/NIF 515734403 e sede na Rua Dr. Eduardo Burnay, 71, 2655-368 Ericeira, \u00e9 a propriet\u00e1ria do diret\u00f3rio e a entidade respons\u00e1vel pelo tratamento dos dados pessoais e cumprimento da legisla\u00e7\u00e3o aplic\u00e1vel quanto a esta mat\u00e9ria.<\/li>\n<li>Os dados pessoais recolhidos ser\u00e3o utilizados unicamente para responder ao seu pedido de contacto ap\u00f3s obtermos o seu consentimento pr\u00e9vio e expresso para o efeito.<\/li>\n<li>Os dados pessoais \u201cnome\u201d e \u201ce-mail\u201d s\u00e3o de preenchimento obrigat\u00f3rio para podermos responder ao seu pedido de contacto atrav\u00e9s de e-mail, pelo que sem estes dados n\u00e3o poderemos realizar o seu pedido ou dar resposta \u00e0 sua quest\u00e3o.<\/li>\n<li>Os dados em quest\u00e3o n\u00e3o ser\u00e3o utilizados para nenhuma outra finalidade sem o seu consentimento pr\u00e9vio, sendo conservados pelo respons\u00e1vel pelo tratamento durante 2 anos.<\/li>\n<li>O respons\u00e1vel pelo tratamento poder\u00e1, ainda, utilizar os dados recolhidos para manter um registo dos seus detalhes de contacto, ap\u00f3s obten\u00e7\u00e3o do seu consentimento pr\u00e9vio para o efeito, sendo estes conservados pelo per\u00edodo de 3 anos.<\/li>\n<li>Relembramos que poder\u00e1 retirar o presente consentimento a qualquer momento.<\/li>\n<li>O respons\u00e1vel pelo tratamento poder\u00e1 comunicar os dados pessoais ao(s) seu(s) prestador(es) de servi\u00e7os para cumprimento da finalidade descrita, ou, a empresas integrantes do grupo empresarial ao qual a respons\u00e1vel pelo tratamento pertence.<\/li>\n<li>Quando nos envia os seus dados pessoais, estes ser\u00e3o protegidos atrav\u00e9s de protocolos de seguran\u00e7a adequados \u00e0s comunica\u00e7\u00f5es via internet e ser\u00e3o conservados num servidor seguro e de acesso condicionado.<\/li>\n<li>Poder\u00e1 exercer os seus direitos previstos na legisla\u00e7\u00e3o (acesso, retifica\u00e7\u00e3o, apagamento, limita\u00e7\u00e3o, oposi\u00e7\u00e3o, portabilidade) atrav\u00e9s de contacto escrito para o seguinte e-mail: <a href=\"mailto:APOIO.CLIENTE@GRUPODASCASAS.PT\">apoio.cliente@grupodascasas.pt<\/a>, sem preju\u00edzo do direito a apresentar reclama\u00e7\u00e3o \u00e0 autoridade de controlo competente (<a href=\"http:\/\/www.cnpd.pt\">cnpd.pt<\/a>).<\/li>\n<\/ol>\n<p>Saiba mais sobre a forma como os seus dados ser\u00e3o tratados\u00a0atrav\u00e9s do e-mail <a href=\"mailto:INFO@GRUPODASCASAS.PT\">INFO@GRUPODASCASAS.PT<\/a>.<\/p>\n<h3><strong>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>DO QUE TRATA ESTA POL\u00cdTICA?<\/u><\/strong><\/h3>\n<ul>\n<li>Esta Pol\u00edtica de Privacidade explica como recolhemos e tratamos os dados pessoais que s\u00e3o necess\u00e1rios para o fornecimento de servi\u00e7os que est\u00e3o dispon\u00edveis atrav\u00e9s do WEBSITE, descrevendo as pr\u00e1ticas adotadas para esse efeito.<\/li>\n<\/ul>\n<h3><strong>2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>O QUE S\u00c3O DADOS PESSOAIS?<\/u><\/strong><\/h3>\n<ul>\n<li>Dados pessoais s\u00e3o todas as informa\u00e7\u00f5es relativas a uma pessoa e que a identificam, ou a tornam identific\u00e1vel, independentemente da natureza e suporte das informa\u00e7\u00f5es, incluindo o som e a imagem da pessoa.<\/li>\n<li>Exemplos de dados pessoais que recolhemos s\u00e3o nome, e-mail, endere\u00e7o de IP e <em>cookies<\/em>.<\/li>\n<li>Por identific\u00e1vel, deve entender-se uma pessoa que possa ser identificada, direta ou indiretamente, designadamente por refer\u00eancia a um n\u00famero de identifica\u00e7\u00e3o ou a outros elementos espec\u00edficos da sua identidade f\u00edsica, fisiol\u00f3gica, ps\u00edquica, econ\u00f3mica, cultural ou social.<\/li>\n<\/ul>\n<h3><strong>3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>COMO VAMOS UTILIZAR OS SEUS DADOS PESSOAIS?<\/u><\/strong><\/h3>\n<p>O Respons\u00e1vel pelo Tratamento ir\u00e1 utilizar os dados pessoais que nos forne\u00e7a para as seguintes finalidades:<\/p>\n<ul>\n<li>Para analisar e responder \u00e0s suas mensagens, apoio ao cliente e pedidos de informa\u00e7\u00e3o;<\/li>\n<li>Para manter um registo dos seus detalhes de contacto;<\/li>\n<li>Para as opera\u00e7\u00f5es de gest\u00e3o do WEBSITE;<\/li>\n<li>Para fins comerciais, como an\u00e1lise de dados, auditorias;<\/li>\n<li>Para preven\u00e7\u00e3o de fraudes e seguran\u00e7a dos sistemas de informa\u00e7\u00e3o;<\/li>\n<li>Para a adapta\u00e7\u00e3o, melhoria e modifica\u00e7\u00e3o dos servi\u00e7os, nomeadamente, atrav\u00e9s da identifica\u00e7\u00e3o de tend\u00eancias de utiliza\u00e7\u00e3o, ou, para determinar a efic\u00e1cia das campanhas promocionais;<\/li>\n<li>Para a expans\u00e3o das atividades comerciais do Respons\u00e1vel pelo Tratamento.<\/li>\n<li>Estas opera\u00e7\u00f5es de tratamento de dados pessoais s\u00e3o uma ferramenta essencial para a sua satisfa\u00e7\u00e3o e para a atividade do Respons\u00e1vel pelo Tratamento e s\u00e3o realizadas de acordo com a legisla\u00e7\u00e3o aplic\u00e1vel e conforme as melhores pr\u00e1ticas.<\/li>\n<li>Os seus dados pessoais n\u00e3o ser\u00e3o reutilizados para outras finalidades que n\u00e3o sejam previamente identificadas ou que n\u00e3o tenham qualquer rela\u00e7\u00e3o com aquelas finalidades para as quais foram inicialmente recolhidos.<\/li>\n<\/ul>\n<h3><strong>4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>QUAIS OS FUNDAMENTOS PARA TRATARMOS OS DADOS PESSOAIS QUE RECOLHEMOS?<\/u><\/strong><\/h3>\n<ul>\n<li>Os dados pessoais que o Respons\u00e1vel pelo Tratamento trata t\u00eam fundamentos espec\u00edficos, consoante as finalidades a que se destinam.<\/li>\n<\/ul>\n<p>Na tabela seguinte pode visualizar quais os fundamentos consoantes as finalidades acima identificadas:<\/p>\n<ul>\n<li>Para analisar e responder \u00e0s suas mensagens, apoio ao cliente e pedidos de informa\u00e7\u00e3o &#8211;<\/li>\n<li>Para manter um registo dos seus detalhes de contacto.<\/li>\n<li>Para as opera\u00e7\u00f5es de gest\u00e3o do WEBSITE<\/li>\n<li>Para fins comerciais, como an\u00e1lise de dados, auditorias.<\/li>\n<li>Para preven\u00e7\u00e3o de fraudes e seguran\u00e7a dos sistemas de informa\u00e7\u00e3o.<\/li>\n<li>Para a adapta\u00e7\u00e3o, melhoria e modifica\u00e7\u00e3o dos servi\u00e7os, nomeadamente, atrav\u00e9s da identifica\u00e7\u00e3o de tend\u00eancias de utiliza\u00e7\u00e3o, ou, para determinar a efic\u00e1cia das campanhas promocionais.<\/li>\n<li>Para a expans\u00e3o das atividades comerciais do Respons\u00e1vel pelo Tratamento.<\/li>\n<\/ul>\n<table style=\"height: 71px;\" border=\"1\" width=\"1070\">\n<tbody>\n<tr>\n<td>Para analisar e responder \u00e0s suas mensagens, apoio ao cliente e pedidos de informa\u00e7\u00e3o<\/td>\n<td>Consentimento para essa finalidade espec\u00edfica<\/td>\n<\/tr>\n<tr>\n<td>Para manter um registo dos seus detalhes de contacto<\/td>\n<td>Consentimento para essa finalidade espec\u00edfica<\/td>\n<\/tr>\n<tr>\n<td>Para as opera\u00e7\u00f5es de gest\u00e3o do WEBSITE<\/td>\n<td>Consentimento para essa finalidade espec\u00edfica (cookies);Interesses leg\u00edtimos prosseguidos pelo Respons\u00e1vel pelo Tratamento<\/td>\n<\/tr>\n<tr>\n<td>Para fins comerciais, como an\u00e1lise de dados, auditorias<\/td>\n<td>Consentimento para essa finalidade espec\u00edfica (cookies);Interesses leg\u00edtimos prosseguidos pelo Respons\u00e1vel pelo Tratamento<\/td>\n<\/tr>\n<tr>\n<td>Para preven\u00e7\u00e3o de fraudes e seguran\u00e7a dos sistemas de informa\u00e7\u00e3o.<\/td>\n<td>Interesses leg\u00edtimos prosseguidos pelo Respons\u00e1vel pelo Tratamento<\/td>\n<\/tr>\n<tr>\n<td>Para a adapta\u00e7\u00e3o, melhoria e modifica\u00e7\u00e3o dos servi\u00e7os, nomeadamente, atrav\u00e9s da identifica\u00e7\u00e3o de tend\u00eancias de utiliza\u00e7\u00e3o, ou, para determinar a efic\u00e1cia das campanhas promocionais.<\/td>\n<td>Consentimento para essa finalidade espec\u00edfica (cookies);Interesses leg\u00edtimos prosseguidos pelo Respons\u00e1vel pelo Tratamento.<\/td>\n<\/tr>\n<tr>\n<td>Para a expans\u00e3o das atividades comerciais do Respons\u00e1vel pelo Tratamento.<\/td>\n<td>Interesses leg\u00edtimos prosseguidos pelo Respons\u00e1vel pelo Tratamento<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\u00a0<\/p>\n<h3><strong>5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>QUE DADOS PESSOAIS RECOLHEMOS?<\/u><\/strong><\/h3>\n<ul>\n<li>Os dados pessoais que o Respons\u00e1vel pelo Tratamento recolhe e trata s\u00e3o apenas aqueles necess\u00e1rios e adequados \u00e0s finalidades acima indicadas.<\/li>\n<li>O Respons\u00e1vel pelo Tratamento ir\u00e1 recolher e tratar os seguintes dados pessoais:<\/li>\n<\/ul>\n<p style=\"padding-left: 80px;\">Para analisar e responder \u00e0s suas mensagens, apoio ao cliente e pedidos de informa\u00e7\u00e3o &#8211; Nome e e-mail Para manter um registo dos seus detalhes de contacto &#8211; Nome e e-mail Para as opera\u00e7\u00f5es de gest\u00e3o do WEBSITE &#8211; Dados de cookies Para fins comerciais, como an\u00e1lise de dados, auditorias &#8211; Dados de cookies Para preven\u00e7\u00e3o de fraudes e seguran\u00e7a dos sistemas de informa\u00e7\u00e3o &#8211; Endere\u00e7o IP; Dados de cookies Para a adapta\u00e7\u00e3o, melhoria e modifica\u00e7\u00e3o dos servi\u00e7os, nomeadamente, atrav\u00e9s da identifica\u00e7\u00e3o de tend\u00eancias de utiliza\u00e7\u00e3o, ou, para determinar a efic\u00e1cia das campanhas promocionais &#8211; Dados de cookies. Para a expans\u00e3o das atividades comerciais do Respons\u00e1vel pelo Tratamento &#8211; Nome e e-mail<\/p>\n<p>\u00a0<\/p>\n<h3><strong>6.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>COMO RECOLHEMOS OS SEUS DADOS PESSOAIS?<\/u><\/strong><\/h3>\n<p>Vamos recolher os seus dados pessoais atrav\u00e9s dos formul\u00e1rios presentes no WEBSITE, mas igualmente atrav\u00e9s do WEBSITE e da comunica\u00e7\u00e3o que este faz com o seu equipamento e mensagens de <em>e-mail<\/em> que nos envia. Os seus dados pessoais s\u00e3o recolhidos atrav\u00e9s do seu equipamento da seguinte forma:<\/p>\n<ul>\n<li>Atrav\u00e9s do seu navegador;<\/li>\n<li>Atrav\u00e9s de <em>cookies<\/em>;<\/li>\n<li>Atrav\u00e9s de <em>pixel<\/em> <em>tags<\/em> e outras tecnologias semelhantes;<\/li>\n<li>Endere\u00e7o IP;<\/li>\n<li>Atrav\u00e9s dos seus dados de Utilizador.<\/li>\n<li>O Respons\u00e1vel pelo Tratamento assume o compromisso de tratar os seus dados conforme a lei e de forma leg\u00edtima.<\/li>\n<li>O Respons\u00e1vel pelo Tratamento n\u00e3o ir\u00e1 vender, nem alugar ou partilhar os seus dados pessoais com terceiros, exceto nos casos claramente identificados nesta Pol\u00edtica de Privacidade (ver Ponto 17 para perceber como).<\/li>\n<li>Os servi\u00e7os do Respons\u00e1vel pelo Tratamento n\u00e3o s\u00e3o dirigidos a menores, n\u00e3o sendo tratados dados pessoais de menores de forma intencional.<\/li>\n<\/ul>\n<h3><strong>7.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>O QUE S\u00c3O COOKIES?<\/u><\/strong><\/h3>\n<ul>\n<li><em>Cookies<\/em> s\u00e3o pequenos arquivos de informa\u00e7\u00f5es que ajudam a identificar o seu browser e que podem armazenar informa\u00e7\u00f5es, por exemplo, configura\u00e7\u00f5es e prefer\u00eancias do Utilizador.<\/li>\n<li>O Respons\u00e1vel pelo Tratamento ir\u00e1 armazenar <em>cookies<\/em> no seu equipamento para personalizar e facilitar ao m\u00e1ximo a navega\u00e7\u00e3o, mas tamb\u00e9m, para a solu\u00e7\u00e3o de problemas, estat\u00edsticas, garantia de qualidade, e para monitorar a seguran\u00e7a do sistema.<\/li>\n<li>Com exce\u00e7\u00e3o dos <em>cookies<\/em> especificamente necess\u00e1rios ao desempenho do website, o armazenamento de outros cookies depender\u00e1 sempre da aceita\u00e7\u00e3o e consentimento do Utilizador, podendo esse consentimento ser retirado a todo o tempo atrav\u00e9s de ferramentas espec\u00edficas do browser.<\/li>\n<\/ul>\n<h3><strong>8.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>COMO UTILIZAMOS COOKIES?.<\/u><\/strong><\/h3>\n<p>Utilizamos <em>cookies<\/em> para apresentar as suas prefer\u00eancias, por exemplo:<\/p>\n<ul>\n<li>Os <em>cookies<\/em> permitem-nos saber se concordou (ou n\u00e3o) com a utiliza\u00e7\u00e3o de cookies no WEBSITE;<\/li>\n<li>Os <em>cookies<\/em> permitem-nos que o identifiquemos como um Utilizador recorrente;<\/li>\n<li>Os <em>cookies<\/em> permitem-nos recuperar as suas prefer\u00eancias personalizadas quando navega;<\/li>\n<li>No ponto <strong>11<\/strong> encontra uma descri\u00e7\u00e3o dos <em>cookies<\/em> utilizados.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<h3><strong>9.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><u> PARA QUE SERVEM OS <em>COOKIES<\/em>?<\/u><\/h3>\n<ul>\n<li>O Respons\u00e1vel pelo Tratamento ir\u00e1 armazenar <em>cookies<\/em> no seu equipamento para personalizar e facilitar ao m\u00e1ximo a navega\u00e7\u00e3o, mas tamb\u00e9m, para a solu\u00e7\u00e3o de problemas, estat\u00edsticas, garantia de qualidade, e para monitorar a seguran\u00e7a do sistema.<\/li>\n<li>Poder\u00e1, a todo o tempo, eliminar ou bloquear os referidos <em>cookies<\/em>, sendo que, ao faz\u00ea-lo, alguns recursos deste WEBSITE poder\u00e3o n\u00e3o funcionar como previsto.<\/li>\n<li>Os <em>cookies<\/em> n\u00e3o s\u00e3o utilizados para quaisquer finalidades que n\u00e3o as aqui descritas.<\/li>\n<\/ul>\n<h3><strong>10.\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>TIPOS DE COOKIES.<\/u><\/strong><\/h3>\n<p>A utiliza\u00e7\u00e3o de <em>cookies <\/em>pode ser dividida nas seguintes categorias:<\/p>\n<ul>\n<li><strong><em>Cookies<\/em><\/strong><strong> Estritamente Necess\u00e1rios<\/strong>: s\u00e3o <em>cookies<\/em> que s\u00e3o essenciais para provis\u00e3o do WEBSITE e para todos os servi\u00e7os solicitados, mas n\u00e3o executam nenhuma fun\u00e7\u00e3o adicional ou secund\u00e1ria.<\/li>\n<li><strong><em>Cookies<\/em><\/strong><strong> de Desempenho<\/strong>: s\u00e3o aqueles <em>cookies<\/em> que fornecem informa\u00e7\u00f5es estat\u00edsticas sobre o uso do WEBSITE, ou seja, a an\u00e1lise da web.<\/li>\n<li><strong><em>Cookies<\/em><\/strong><strong> de Segmenta\u00e7\u00e3o\/Publicidade<\/strong>: s\u00e3o <em>cookies<\/em> utilizados para criar perfis ou personalizar conte\u00fados.<\/li>\n<\/ul>\n<h3><strong>11.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>COOKIES QUE UTILIZAMOS.<\/u><\/strong><\/h3>\n<h3><strong>Cookies Estritamente Necess\u00e1rio<\/strong><\/h3>\n<p>Origem: <em>Pr\u00f3prios <\/em><em>(.grupodascasas.pt)<\/em> Nome: <em>__cfduid<\/em> Descri\u00e7\u00e3o: <em>Cookie associado a websites que utilizam CloudFare, para acelerar o tempo de carregamento dos mesmos. O cookie \u00e9 utilizado para substituir restri\u00e7\u00f5es de seguran\u00e7a com base no endere\u00e7o de IP do qual o utilizador prov\u00e9m.<\/em> Dura\u00e7\u00e3o: 1 ano<\/p>\n<h3><strong>12.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>CONTROLO E GEST\u00c3O DE COOKIES.<\/u><\/strong><\/h3>\n<ul>\n<li>A todo o tempo poder\u00e1 controlar e\/ou eliminar os <em>cookies<\/em>, nomeadamente, poder\u00e1 eliminar todos os <em>cookies<\/em> que j\u00e1 estejam armazenados no seu equipamento, podendo inclusivamente configurar a maioria dos <em>browsers<\/em> de forma a prevenir o seu armazenamento.<\/li>\n<li>Para que consiga efetuar essa gest\u00e3o, ter\u00e1, no entanto, que ajustar manualmente algumas prefer\u00eancias de cada vez que visita determinados websites<em>,<\/em> sem as quais alguns servi\u00e7os e funcionalidades poder\u00e3o n\u00e3o funcionar.<\/li>\n<li>Como garantia adicional poder\u00e1, a todo o tempo, desativar os <em>cookies<\/em>, configurando o seu <em>browser<\/em>, de acordo com as instru\u00e7\u00f5es dispon\u00edveis em:\n<ul>\n<li>Para utilizadores do Google Chrome: <a href=\"http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=en&amp;answer=95647\">http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=en&amp;answer=95647<\/a><\/li>\n<li>Para utilizadores do Internet Explorer: <a href=\"https:\/\/support.microsoft.com\/pt-pt\/help\/17442\/windows-internet-explorer-delete-manage-cookies\">https:\/\/support.microsoft.com\/pt-pt\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/a><\/li>\n<li>Para utilizadores do Microsoft Edge: <a href=\"https:\/\/privacy.microsoft.com\/en-us\/windows-10-microsoft-edge-and-privacy\">https:\/\/privacy.microsoft.com\/en-us\/windows-10-microsoft-edge-and-privacy<\/a><\/li>\n<li>Para utilizadores do Mozilla Firefox: <a href=\"https:\/\/support.mozilla.org\/en-US\/kb\/enable-and-disable-cookies-website-preferences\">https:\/\/support.mozilla.org\/en-US\/kb\/enable-and-disable-cookies-website-preferences<\/a><\/li>\n<li>Para utilizadores do Apple Safari: <a href=\"http:\/\/support.apple.com\/kb\/ph5042\">http:\/\/support.apple.com\/kb\/ph5042<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3><strong>13.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>O QUE S\u00c3O <em>PIXEL TAGS<\/em> E OUTRAS TECNOLOGIAS SEMELHANTES?<\/u><\/strong><\/h3>\n<ul>\n<li>Os <em>pixel<\/em> <em>tags<\/em> (tamb\u00e9m conhecidos como <em>web beacons<\/em> e <em>clear GIFs<\/em>) podem ser usados em conex\u00e3o com alguns servi\u00e7os para, por exemplo, acompanhar as a\u00e7\u00f5es dos utilizadores dos servi\u00e7os (incluindo destinat\u00e1rios de e-mail), medir o sucesso das nossas campanhas de marketing e compilar estat\u00edsticas sobre a utiliza\u00e7\u00e3o dos Servi\u00e7os e taxas de resposta.<\/li>\n<\/ul>\n<h3><strong>14.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>COMO PROTEGEMOS OS SEUS DADOS PESSOAIS?<\/u><\/strong><\/h3>\n<ul>\n<li>Os seus dados pessoais s\u00e3o mantidos em seguran\u00e7a atrav\u00e9s da ado\u00e7\u00e3o de diversas medidas de seguran\u00e7a, de car\u00e1ter t\u00e9cnico e organizativo que garantem que s\u00f3 t\u00eam acesso aos dados pessoais os Colaboradores que devem aceder aos mesmos, conforme regras criadas para o efeito.<\/li>\n<li>Para proteger os seus dados pessoais s\u00f3 recorremos a fornecedores de centros de dados que nos ofere\u00e7am medidas de seguran\u00e7a adequadas e documentadas, nomeadamente, garantias que os seus dados pessoais s\u00e3o armazenados em servidores que s\u00e3o mantidos em ambientes controlados com acessos limitados.<\/li>\n<li>De igual modo, quando navega no WEBSITE, protegemos os seus dados com criptografia, como por exemplo, Transport Layer Security (TLS, \u00e9 um protocolo de seguran\u00e7a que protege as telecomunica\u00e7\u00f5es via internet).<\/li>\n<li>Embora tomemos os cuidados e as precau\u00e7\u00f5es que entendemos adequadas para proteger os dados pessoais que nos fornece e recolhemos, \u00e9 preciso ter consci\u00eancia que nenhum sistema de seguran\u00e7a \u00e9 impenetr\u00e1vel.<\/li>\n<\/ul>\n<h3><strong>15.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>QUANTO TEMPO CONSERVAMOS OS SEUS DADOS PESSOAIS?<\/u><\/strong><\/h3>\n<p>Os seus dados pessoais ser\u00e3o conservados pelo tempo necess\u00e1rio \u00e0s finalidades a que se destinam, conforme elencado nesta Pol\u00edtica de Privacidade. Assim:<\/p>\n<ul>\n<li>Para analisar e responder \u00e0s suas mensagens, apoio ao cliente e pedidos de informa\u00e7\u00e3o: 2 anos.<\/li>\n<li>Para manter um registo dos seus detalhes de contacto: 3 anos.<\/li>\n<li>Para as opera\u00e7\u00f5es de gest\u00e3o do WEBSITE:2 anos.<\/li>\n<li>Para fins comerciais, como an\u00e1lise de dados, auditorias: 2 anos.<\/li>\n<li>Para preven\u00e7\u00e3o de fraudes e seguran\u00e7a dos sistemas de informa\u00e7\u00e3o:2 anos.<\/li>\n<li>Para a adapta\u00e7\u00e3o, melhoria e modifica\u00e7\u00e3o dos servi\u00e7os, nomeadamente, atrav\u00e9s da identifica\u00e7\u00e3o de tend\u00eancias de utiliza\u00e7\u00e3o, ou, para determinar a efic\u00e1cia das campanhas promocionais:3 ano<\/li>\n<li>Caso resulte da lei algum per\u00edodo espec\u00edfico ou obrigat\u00f3rio, o per\u00edodo de conserva\u00e7\u00e3o dos dados ser\u00e1 esse. Em todos os outros casos, os dados pessoais ser\u00e3o conservados no m\u00e1ximo durante os tempos acima indicados, per\u00edodos que o Respons\u00e1vel pelo Tratamento entende como suficiente para cumprimento das finalidades.<\/li>\n<li>Findo o per\u00edodo de conserva\u00e7\u00e3o, todos os dados pessoais recolhidos ser\u00e3o eliminados.<\/li>\n<\/ul>\n<h3><strong>16.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>COMO PODE EXERCER OS SEUS DIREITOS:<\/u><\/strong><\/h3>\n<p>Antes de explicarmos como pode exercer os seus direitos, conv\u00e9m saber quais s\u00e3o. Assim, a legisla\u00e7\u00e3o atribui-lhe o direito de nos solicitar o exerc\u00edcio dos seguintes direitos:<\/p>\n<ul>\n<li><u>Acesso<\/u>: direito de obter a confirma\u00e7\u00e3o de que os dados pessoais que lhe digam respeito s\u00e3o ou n\u00e3o objeto de tratamento e, se for esse o caso, o direito de aceder aos seus dados pessoais;<\/li>\n<li><u>Retifica\u00e7\u00e3o<\/u>: o direito de obter a retifica\u00e7\u00e3o dos dados pessoais inexatos que lhe digam respeito e a que os seus dados pessoais incompletos sejam completados;<\/li>\n<li><u>Apagamento<\/u>: o direito de obter o apagamento dos seus dados pessoais quando se aplique um dos motivos elencados na legisla\u00e7\u00e3o;<\/li>\n<li><u>Limita\u00e7\u00e3o do tratamento<\/u>: o direito de obter a limita\u00e7\u00e3o do tratamento se se aplicar uma das situa\u00e7\u00f5es elencadas na legisla\u00e7\u00e3o;<\/li>\n<li><u>Oposi\u00e7\u00e3o<\/u>: o direito de se opor a qualquer momento ao tratamento dos dados pessoais que lhe digam respeito;<\/li>\n<li><u>Portabilidade<\/u>: o direito de receber os dados pessoais que lhe digam respeito num formato estruturado, de uso corrente e de leitura autom\u00e1tica.<\/li>\n<li>Tem ainda o direito de apresentar reclama\u00e7\u00e3o junto \u00e0 autoridade de controlo competente (em Portugal, a Comiss\u00e3o Nacional de Prote\u00e7\u00e3o de Dados em www.cnpd.pt)<\/li>\n<li>Para efeito do exerc\u00edcio dos direitos acima indicados dever\u00e1 contactar o Respons\u00e1vel pelo Tratamento atrav\u00e9s do seguinte e-mail<em> [EMAIL]<\/em><\/li>\n<li>Caso nos solicite a elimina\u00e7\u00e3o de alguns dos seus dados pessoais ou da sua totalidade, alguns dos servi\u00e7os solicitados poder\u00e3o n\u00e3o lhe ser prestados e o Respons\u00e1vel pelo Tratamento ir\u00e1 conservar apenas os dados pessoais necess\u00e1rios para o cumprimento das obriga\u00e7\u00f5es legais a que se encontra vinculada.<\/li>\n<\/ul>\n<h3><strong>17.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>QUANDO COMUNICAMOS DADOS A TERCEIROS?<\/u><\/strong><\/h3>\n<ul>\n<li>O Respons\u00e1vel pelo Tratamento poder\u00e1 recorrer a terceiros para a presta\u00e7\u00e3o de determinados servi\u00e7os, a n\u00edvel de manuten\u00e7\u00e3o e de apoio t\u00e9cnico, nomeadamente, podendo estes ter acesso a alguns dos dados pessoais, nomeadamente, os dados necess\u00e1rios para os fins contratualizados.<\/li>\n<li>O Respons\u00e1vel pelo Tratamento assegura que as entidades que tenham acesso aos dados s\u00e3o cred\u00edveis e oferecem elevadas garantias de prote\u00e7\u00e3o, nunca lhes sendo transmitidos dados para al\u00e9m do necess\u00e1rio \u00e0 presta\u00e7\u00e3o do servi\u00e7o contratado, permanecendo, contudo, aquele, como respons\u00e1vel pelos dados pessoais disponibilizados.<\/li>\n<li><em>Por exemplo, para efeitos de gest\u00e3o de centro de dados, a [EMPRESA] recorre aos servi\u00e7os da [EMPRESA 2].<\/em><\/li>\n<li>O Respons\u00e1vel pelo Tratamento poder\u00e1 ainda comunicar os seus dados \u00e0s seguintes entidades:\n<ul>\n<li>Empresas do grupo empresarial ao qual o Respons\u00e1vel pelo Tratamento pertence e com que tenha parcerias comerciais para a cria\u00e7\u00e3o e oferta de benef\u00edcios; ou ainda,<\/li>\n<li>Outros parceiros fora do seu grupo empresarial (com autoriza\u00e7\u00e3o pr\u00e9via da sua parte).<\/li>\n<li>O Respons\u00e1vel pelo Tratamento poder\u00e1 ainda transmitir dados a terceiros no \u00e2mbito de investiga\u00e7\u00f5es, inqu\u00e9ritos e processos judiciais e\/ou administrativos ou de natureza semelhante, desde que para tal seja devidamente ordenada por ordem judicial nesse sentido.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3 style=\"padding-left: 40px;\"><strong>18.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>WEBSITES DE TERCEIROS.<\/u><\/strong><\/h3>\n<ul>\n<li>O WEBSITE poder\u00e1 conter liga\u00e7\u00f5es para outros websites os quais poder\u00e3o recolher tratar os seus dados pessoais e, esse tratamento \u00e9 da exclusiva responsabilidade dos propriet\u00e1rios desses websites, n\u00e3o tendo o Respons\u00e1vel pelo Tratamento qualquer responsabilidade pelas suas pol\u00edticas e\/ou pr\u00e1ticas.<\/li>\n<li>Exemplo desses terceiros \u00e9 o <em>Facebook, <\/em>atrav\u00e9s dos bot\u00f5es que est\u00e3o presentes no WEBSITE.<\/li>\n<\/ul>\n<h3><strong>19.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>TRANSFER\u00caNCIAS DE DADOS PARA FORA DA UNI\u00c3O EUROPEIA.<\/u><\/strong><\/h3>\n<ul>\n<li>Caso possam ocorrer transfer\u00eancias de dados para pa\u00edses terceiros que n\u00e3o pertencendo \u00e0 Uni\u00e3o Europeia, o Respons\u00e1vel pelo Tratamento cumprir\u00e1 com as regras legais, nomeadamente no que respeita \u00e0 adequabilidade do pa\u00eds de destino relativamente \u00e0 prote\u00e7\u00e3o de dados pessoais e aos requisitos, que s\u00e3o aplic\u00e1veis a estas transfer\u00eancias, n\u00e3o sendo transferidos dados pessoais para jurisdi\u00e7\u00f5es que n\u00e3o ofere\u00e7am garantias de seguran\u00e7a e prote\u00e7\u00e3o.<\/li>\n<\/ul>\n<h3><strong>20.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>OS MENORES.<\/u><\/strong><\/h3>\n<ul>\n<li>O WEBSITE n\u00e3o \u00e9 dirigido a menores de 16 anos, pelo que solicitamos que estes menores n\u00e3o nos forne\u00e7am dados pessoais atrav\u00e9s do WEBSITE, aplica\u00e7\u00e3o, redes sociais e social media ou e-mails.<\/li>\n<\/ul>\n<h3><strong>21.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>DADOS PESSOAIS SENS\u00cdVEIS.<\/u><\/strong><\/h3>\n<ul>\n<li>O Respons\u00e1vel pelo Tratamento agradece que n\u00e3o nos envie nem nos d\u00ea a conhecer quaisquer dados pessoais sens\u00edveis, ou seja, informa\u00e7\u00f5es que revelem a origem racial ou \u00e9tnica, opini\u00f5es pol\u00edticas, cren\u00e7as religiosas ou filos\u00f3ficas, associa\u00e7\u00e3o sindical, informa\u00e7\u00f5es gen\u00e9ticas, informa\u00e7\u00f5es biom\u00e9tricas, dados relativos \u00e0 sa\u00fade ou dados relativos a vida sexual de uma pessoa natural ou a orienta\u00e7\u00e3o sexual.<\/li>\n<li>Caso ainda assim nos envie ou d\u00ea a conhecer essas categorias de dados pessoais, estes ser\u00e3o imediatamente apagados.<\/li>\n<\/ul>\n<h3><strong>22.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>ALTERA\u00c7\u00d5ES \u00c0 POL\u00cdTICA DE PRIVACIDADE.<\/u><\/strong><\/h3>\n<ul>\n<li>O Respons\u00e1vel pelo Tratamento reserva-se no direito de reajustar ou alterar a presente Pol\u00edtica de Privacidade, a qualquer momento, sendo essas altera\u00e7\u00f5es publicitadas.<\/li>\n<\/ul>\n<h3><strong>23.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>OS NOSSOS DETALHES DE CONTACTO.<\/u><\/strong><\/h3>\n<ul>\n<li>Caso tenha alguma d\u00favida ou quest\u00e3o relacionada com esta Pol\u00edtica de Privacidade por favor contacte-nos por escrito atrav\u00e9s do <em>e-mail<\/em> <a href=\"mailto:APOIO.CLIENTE@GRUPODASCASAS.PT\">APOIO.CLIENTE@GRUPODASCASAS.PT<\/a>.<\/li>\n<\/ul>\n<h3><strong>24.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>\u00daLTIMA VERS\u00c3O.<\/u><\/strong><\/h3>\n<p>13.12.2019<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>O A RJRI \u2013 A CASA DAS COMUNICA\u00c7\u00d5ES, LDA. (doravante, \u201cRespons\u00e1vel pelo Tratamento\u201d), com sede na Rua Dr. Eduardo Burnay, 71, 2655-368 Ericeira, e NIPC 515734403 \u00e9 propriet\u00e1rio do dom\u00ednio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Privacidade e Cookies - Ericeira Market<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ericeiramarket.pt\/en\/politica-de-privacidade-e-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidade e Cookies - Ericeira Market\" \/>\n<meta property=\"og:description\" content=\"O A RJRI \u2013 A CASA DAS COMUNICA\u00c7\u00d5ES, LDA. (doravante, \u201cRespons\u00e1vel pelo Tratamento\u201d), com sede na Rua Dr. Eduardo Burnay, 71, 2655-368 Ericeira, e NIPC 515734403 \u00e9 propriet\u00e1rio do dom\u00ednio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ericeiramarket.pt\/en\/politica-de-privacidade-e-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Ericeira Market\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EriceiraMarket\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-09T16:10:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ericeiramarket.pt\/wp-content\/uploads\/2020\/09\/Asset-4ericeira-market-logos-seo.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/politica-de-privacidade-e-cookies\\\/\",\"url\":\"https:\\\/\\\/ericeiramarket.pt\\\/politica-de-privacidade-e-cookies\\\/\",\"name\":\"Pol\u00edtica de Privacidade e Cookies - Ericeira Market\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#website\"},\"datePublished\":\"2022-01-21T11:55:58+00:00\",\"dateModified\":\"2022-03-09T16:10:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/politica-de-privacidade-e-cookies\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ericeiramarket.pt\\\/politica-de-privacidade-e-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/politica-de-privacidade-e-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ericeiramarket.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Privacidade e Cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#website\",\"url\":\"https:\\\/\\\/ericeiramarket.pt\\\/\",\"name\":\"Ericeira Market\",\"description\":\"O melhor da Ericeira est\u00e1 aqui!\",\"publisher\":{\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ericeiramarket.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#organization\",\"name\":\"Ericeira Market - A Ericeira cabe toda aqui\",\"url\":\"https:\\\/\\\/ericeiramarket.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ericeiramarket.pt\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Asset-4ericeira-market-logos-seo.png\",\"contentUrl\":\"https:\\\/\\\/ericeiramarket.pt\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Asset-4ericeira-market-logos-seo.png\",\"width\":557,\"height\":566,\"caption\":\"Ericeira Market - A Ericeira cabe toda aqui\"},\"image\":{\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EriceiraMarket\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy and Cookie Policy - Ericeira Market","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ericeiramarket.pt\/en\/politica-de-privacidade-e-cookies\/","og_locale":"en_GB","og_type":"article","og_title":"Pol\u00edtica de Privacidade e Cookies - Ericeira Market","og_description":"O A RJRI \u2013 A CASA DAS COMUNICA\u00c7\u00d5ES, LDA. (doravante, \u201cRespons\u00e1vel pelo Tratamento\u201d), com sede na Rua Dr. Eduardo Burnay, 71, 2655-368 Ericeira, e NIPC 515734403 \u00e9 propriet\u00e1rio do dom\u00ednio [&hellip;]","og_url":"https:\/\/ericeiramarket.pt\/en\/politica-de-privacidade-e-cookies\/","og_site_name":"Ericeira Market","article_publisher":"https:\/\/www.facebook.com\/EriceiraMarket\/","article_modified_time":"2022-03-09T16:10:26+00:00","og_image":[{"url":"https:\/\/ericeiramarket.pt\/wp-content\/uploads\/2020\/09\/Asset-4ericeira-market-logos-seo.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ericeiramarket.pt\/politica-de-privacidade-e-cookies\/","url":"https:\/\/ericeiramarket.pt\/politica-de-privacidade-e-cookies\/","name":"Privacy and Cookie Policy - Ericeira Market","isPartOf":{"@id":"https:\/\/ericeiramarket.pt\/#website"},"datePublished":"2022-01-21T11:55:58+00:00","dateModified":"2022-03-09T16:10:26+00:00","breadcrumb":{"@id":"https:\/\/ericeiramarket.pt\/politica-de-privacidade-e-cookies\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ericeiramarket.pt\/politica-de-privacidade-e-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ericeiramarket.pt\/politica-de-privacidade-e-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ericeiramarket.pt\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidade e Cookies"}]},{"@type":"WebSite","@id":"https:\/\/ericeiramarket.pt\/#website","url":"https:\/\/ericeiramarket.pt\/","name":"Ericeira Market","description":"The best of Ericeira is here!","publisher":{"@id":"https:\/\/ericeiramarket.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ericeiramarket.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ericeiramarket.pt\/#organization","name":"Ericeira Market - Ericeira fits in here","url":"https:\/\/ericeiramarket.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ericeiramarket.pt\/#\/schema\/logo\/image\/","url":"https:\/\/ericeiramarket.pt\/wp-content\/uploads\/2020\/09\/Asset-4ericeira-market-logos-seo.png","contentUrl":"https:\/\/ericeiramarket.pt\/wp-content\/uploads\/2020\/09\/Asset-4ericeira-market-logos-seo.png","width":557,"height":566,"caption":"Ericeira Market - A Ericeira cabe toda aqui"},"image":{"@id":"https:\/\/ericeiramarket.pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EriceiraMarket\/"]}]}},"_links":{"self":[{"href":"https:\/\/ericeiramarket.pt\/en\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ericeiramarket.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ericeiramarket.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ericeiramarket.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ericeiramarket.pt\/en\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/ericeiramarket.pt\/en\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/ericeiramarket.pt\/en\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}