{"id":87,"count":199,"description":"","link":"https:\/\/ericeiramarket.pt\/en\/empresas-categoria\/restaurantes\/","name":"Restaurants","slug":"restaurantes","taxonomy":"job_listing_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurantes Archives - Ericeira Market<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ericeiramarket.pt\/en\/empresas-categoria\/restaurantes\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurantes Archives - Ericeira Market\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ericeiramarket.pt\/en\/empresas-categoria\/restaurantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Ericeira Market\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ericeiramarket.pt\/wp-content\/uploads\/2020\/09\/Asset-4ericeira-market-logos-seo.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/empresas-categoria\\\/restaurantes\\\/\",\"url\":\"https:\\\/\\\/ericeiramarket.pt\\\/empresas-categoria\\\/restaurantes\\\/\",\"name\":\"Restaurantes Archives - Ericeira Market\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/empresas-categoria\\\/restaurantes\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/empresas-categoria\\\/restaurantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ericeiramarket.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#website\",\"url\":\"https:\\\/\\\/ericeiramarket.pt\\\/\",\"name\":\"Ericeira Market\",\"description\":\"O melhor da Ericeira est\u00e1 aqui!\",\"publisher\":{\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ericeiramarket.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#organization\",\"name\":\"Ericeira Market - A Ericeira cabe toda aqui\",\"url\":\"https:\\\/\\\/ericeiramarket.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ericeiramarket.pt\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Asset-4ericeira-market-logos-seo.png\",\"contentUrl\":\"https:\\\/\\\/ericeiramarket.pt\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Asset-4ericeira-market-logos-seo.png\",\"width\":557,\"height\":566,\"caption\":\"Ericeira Market - A Ericeira cabe toda aqui\"},\"image\":{\"@id\":\"https:\\\/\\\/ericeiramarket.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EriceiraMarket\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurantes Archives - Ericeira Market","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ericeiramarket.pt\/en\/empresas-categoria\/restaurantes\/","og_locale":"en_GB","og_type":"article","og_title":"Restaurantes Archives - Ericeira Market","og_url":"https:\/\/ericeiramarket.pt\/en\/empresas-categoria\/restaurantes\/","og_site_name":"Ericeira Market","og_image":[{"url":"https:\/\/ericeiramarket.pt\/wp-content\/uploads\/2020\/09\/Asset-4ericeira-market-logos-seo.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ericeiramarket.pt\/empresas-categoria\/restaurantes\/","url":"https:\/\/ericeiramarket.pt\/empresas-categoria\/restaurantes\/","name":"Restaurants Archives - Ericeira Market","isPartOf":{"@id":"https:\/\/ericeiramarket.pt\/#website"},"breadcrumb":{"@id":"https:\/\/ericeiramarket.pt\/empresas-categoria\/restaurantes\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/ericeiramarket.pt\/empresas-categoria\/restaurantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ericeiramarket.pt\/"},{"@type":"ListItem","position":2,"name":"Restaurantes"}]},{"@type":"WebSite","@id":"https:\/\/ericeiramarket.pt\/#website","url":"https:\/\/ericeiramarket.pt\/","name":"Ericeira Market","description":"The best of Ericeira is here!","publisher":{"@id":"https:\/\/ericeiramarket.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ericeiramarket.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ericeiramarket.pt\/#organization","name":"Ericeira Market - Ericeira fits in here","url":"https:\/\/ericeiramarket.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ericeiramarket.pt\/#\/schema\/logo\/image\/","url":"https:\/\/ericeiramarket.pt\/wp-content\/uploads\/2020\/09\/Asset-4ericeira-market-logos-seo.png","contentUrl":"https:\/\/ericeiramarket.pt\/wp-content\/uploads\/2020\/09\/Asset-4ericeira-market-logos-seo.png","width":557,"height":566,"caption":"Ericeira Market - A Ericeira cabe toda aqui"},"image":{"@id":"https:\/\/ericeiramarket.pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EriceiraMarket\/"]}]}},"_links":{"self":[{"href":"https:\/\/ericeiramarket.pt\/en\/wp-json\/wp\/v2\/job-categories\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ericeiramarket.pt\/en\/wp-json\/wp\/v2\/job-categories"}],"about":[{"href":"https:\/\/ericeiramarket.pt\/en\/wp-json\/wp\/v2\/taxonomies\/job_listing_category"}]}}